{"id":2112,"date":"2025-12-05T10:37:59","date_gmt":"2025-12-05T10:37:59","guid":{"rendered":"https:\/\/serviceshop.a.aedlab.nl\/?post_type=klantverhaal&#038;p=2112"},"modified":"2026-07-16T10:14:22","modified_gmt":"2026-07-16T08:14:22","slug":"technische-unie","status":"publish","type":"klantverhaal","link":"https:\/\/serviceshop.a.aedlab.nl\/be\/klantverhaal\/technische-unie\/","title":{"rendered":"AED\u2019s voor Technische Unie \u00e9n de Roparun"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Technische Unie is een groothandel in technische installatiematerialen voor bouw, installatie en industrie. Groothandel met de nadruk op GROOT: bij elkaar werken er maar liefst 2.200 mensen. Hoe zorg je dat zij allemaal (hart)veilig kunnen werken? Onder meer met AED\u2019s!<br><br><\/strong>Nico Boerman is Manager Security en Bedrijfshulpverlening bij Technische Unie:<em><br>\u201cWe hebben in totaal ongeveer 50 AED\u2019s, verspreid over diverse vestigingen en pick-up points. Het onderhoud van deze AED\u2019s regelen we zelf: we vervangen de batterijen en elektroden al 17 jaar binnenshuis. Dit jaar kwamen we echter op het punt dat een groot deel van die AED\u2019s hun maximale leeftijd bereikt hadden: ze waren echt toe aan vervanging. In het verleden zijn we al eens goed en snel door AED-Partner geholpen en daarom klopten we weer bij hen aan voor advies. En dat is wederom goed bevallen!<br><br>Meteen na ons akkoord op de offerte, belde een medewerker van AED-Partner ons op met \u2018Bedankt, hartstikke leuk!\u2019 en heeft ze alles tot in de puntjes geregeld. Inmiddels zijn onze nieuwe Mindray AED\u2019s binnen en zijn we bezig om ze te plaatsen. Mooi is dat we de draagbeugels van de oude AED\u2019s kunnen hergebruiken; de nieuwe AED\u2019s passen daar inclusief draagtas perfect in.\u201d<\/em><strong><br><br>N\u00f3g meer AED\u2019s: AED-Partner sponsort Roparun<\/strong><br>Ook buiten de werkvloer is Technische Unie in de weer met AED\u2019s. Elk jaar doet het bedrijf namelijk mee aan de Roparun: een estafetteloop van Parijs naar Rotterdam. Het doel: geld ophalen voor palliatieve zorg voor mensen met kanker. Een avontuur voor het leven dus.<br><br>Naast genoeg eten, drinken en verbanddozen nemen de teams van Technische Unie sinds een paar jaar ook altijd enkele AED\u2019s mee. Nico:\u00a0<em>\u201cAED-Partner heeft deze AED\u2019s voor het derde jaar op rij gesponsord. Dank jullie wel! Mede dankzij jullie sponsoring zijn onze teams ook dit jaar weer veilig gefinisht \u00e9n hebben we \u20ac 58.100,- op kunnen halen!\u201d<br><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nico Boerman<br>Manager Security en Bedrijfshulpverlening<br><em>Technische Unie<\/em><\/p>","protected":false},"featured_media":2135,"template":"","meta":{"_acf_changed":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":""},"class_list":["post-2112","klantverhaal","type-klantverhaal","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Technische-unie - AED\u2019s voor Technische Unie \u00e9n de Roparun - AED-Partner<\/title>\n<meta name=\"description\" content=\"AED-Partner heeft deze AED\u2019s voor het derde jaar op rij gesponsord. Dank jullie wel! Mede dankzij jullie sponsoring zijn onze teams ook dit jaar weer veilig gefinisht \u00e9n hebben we \u20ac 58.100,- op kunnen halen!\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technische-unie - AED\u2019s voor Technische Unie \u00e9n de Roparun - AED-Partner\" \/>\n<meta property=\"og:description\" content=\"AED-Partner heeft deze AED\u2019s voor het derde jaar op rij gesponsord. Dank jullie wel! Mede dankzij jullie sponsoring zijn onze teams ook dit jaar weer veilig gefinisht \u00e9n hebben we \u20ac 58.100,- op kunnen halen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/\" \/>\n<meta property=\"og:site_name\" content=\"AED-Partner\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-16T08:14:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2025\/12\/roparun.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"892\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/klantverhaal\\\/technische-unie\\\/\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/klantverhaal\\\/technische-unie\\\/\",\"name\":\"Technische-unie - AED\u2019s voor Technische Unie \u00e9n de Roparun - AED-Partner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/klantverhaal\\\/technische-unie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/klantverhaal\\\/technische-unie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/roparun.jpg\",\"datePublished\":\"2025-12-05T10:37:59+00:00\",\"dateModified\":\"2026-07-16T08:14:22+00:00\",\"description\":\"AED-Partner heeft deze AED\u2019s voor het derde jaar op rij gesponsord. Dank jullie wel! Mede dankzij jullie sponsoring zijn onze teams ook dit jaar weer veilig gefinisht \u00e9n hebben we \u20ac 58.100,- op kunnen halen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/klantverhaal\\\/technische-unie\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serviceshop.aedlab.nl\\\/klantverhaal\\\/technische-unie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/klantverhaal\\\/technische-unie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/roparun.jpg\",\"contentUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/roparun.jpg\",\"width\":1200,\"height\":892,\"caption\":\"AED's worden gebruiksklaar gemaakt voor Roparun\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/klantverhaal\\\/technische-unie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AED\u2019s voor Technische Unie \u00e9n de Roparun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#website\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/\",\"name\":\"Aedpartner.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#organization\",\"name\":\"AED-Partner\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-Logo-RGB-scaled.png\",\"contentUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-Logo-RGB-scaled.png\",\"width\":2560,\"height\":1372,\"caption\":\"AED-Partner\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Technische-unie - AED\u2019s voor Technische Unie \u00e9n de Roparun - AED-Partner","description":"AED-Partner heeft deze AED\u2019s voor het derde jaar op rij gesponsord. Dank jullie wel! Mede dankzij jullie sponsoring zijn onze teams ook dit jaar weer veilig gefinisht \u00e9n hebben we \u20ac 58.100,- op kunnen halen!","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_BE","og_type":"article","og_title":"Technische-unie - AED\u2019s voor Technische Unie \u00e9n de Roparun - AED-Partner","og_description":"AED-Partner heeft deze AED\u2019s voor het derde jaar op rij gesponsord. Dank jullie wel! Mede dankzij jullie sponsoring zijn onze teams ook dit jaar weer veilig gefinisht \u00e9n hebben we \u20ac 58.100,- op kunnen halen!","og_url":"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/","og_site_name":"AED-Partner","article_modified_time":"2026-07-16T08:14:22+00:00","og_image":[{"width":1200,"height":892,"url":"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2025\/12\/roparun.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/","url":"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/","name":"Technische-unie - AED\u2019s voor Technische Unie \u00e9n de Roparun - AED-Partner","isPartOf":{"@id":"https:\/\/serviceshop.aedlab.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/#primaryimage"},"image":{"@id":"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/#primaryimage"},"thumbnailUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/12\/roparun.jpg","datePublished":"2025-12-05T10:37:59+00:00","dateModified":"2026-07-16T08:14:22+00:00","description":"AED-Partner heeft deze AED\u2019s voor het derde jaar op rij gesponsord. Dank jullie wel! Mede dankzij jullie sponsoring zijn onze teams ook dit jaar weer veilig gefinisht \u00e9n hebben we \u20ac 58.100,- op kunnen halen!","breadcrumb":{"@id":"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/#primaryimage","url":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/12\/roparun.jpg","contentUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/12\/roparun.jpg","width":1200,"height":892,"caption":"AED's worden gebruiksklaar gemaakt voor Roparun"},{"@type":"BreadcrumbList","@id":"https:\/\/serviceshop.aedlab.nl\/klantverhaal\/technische-unie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serviceshop.aedlab.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"AED\u2019s voor Technische Unie \u00e9n de Roparun"}]},{"@type":"WebSite","@id":"https:\/\/serviceshop.aedlab.nl\/#website","url":"https:\/\/serviceshop.aedlab.nl\/","name":"Aedpartner.com","description":"","publisher":{"@id":"https:\/\/serviceshop.aedlab.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serviceshop.aedlab.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/serviceshop.aedlab.nl\/#organization","name":"AED-Partner","url":"https:\/\/serviceshop.aedlab.nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/serviceshop.aedlab.nl\/#\/schema\/logo\/image\/","url":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-Logo-RGB-scaled.png","contentUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-Logo-RGB-scaled.png","width":2560,"height":1372,"caption":"AED-Partner"},"image":{"@id":"https:\/\/serviceshop.aedlab.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be\/wp-json\/wp\/v2\/klantverhaal\/2112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be\/wp-json\/wp\/v2\/klantverhaal"}],"about":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be\/wp-json\/wp\/v2\/types\/klantverhaal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serviceshop.a.aedlab.nl\/be\/wp-json\/wp\/v2\/media\/2135"}],"wp:attachment":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be\/wp-json\/wp\/v2\/media?parent=2112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}