{"id":1215,"date":"2022-05-31T11:25:27","date_gmt":"2022-05-31T11:25:27","guid":{"rendered":"https:\/\/serviceshop.a.aedlab.nl\/?p=1215"},"modified":"2026-07-06T15:28:28","modified_gmt":"2026-07-06T13:28:28","slug":"een-hartveilige-stad-eindhoven","status":"publish","type":"post","link":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/een-hartveilige-stad-eindhoven\/","title":{"rendered":"Une ville s\u00fbre pour le c\u0153ur \u00e0 Eindhoven"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Il est temps d'agir ! Nous avons r\u00e9alis\u00e9 qu'il y avait encore trop d'endroits \u00e0 Eindhoven o\u00f9 une aide ne pourrait pas \u00eatre fournie en moins de 6 minutes en cas d'arr\u00eat cardiaque. \u00c0 partir de cette prise de conscience douloureuse, nous avons commenc\u00e9 \u00e0 \u00e9laborer un plan pour rendre la ville d'Eindhoven plus s\u00fbre en mati\u00e8re de sant\u00e9 cardiaque. C'est \u00e0 ce moment-l\u00e0 qu'a d\u00e9but\u00e9 l'intense collaboration avec la Stichting Eindhoven Hartveilig afin de pouvoir avoir un impact local. Nous avons cartographi\u00e9 avec pr\u00e9cision o\u00f9 des DAE suppl\u00e9mentaires \u00e9taient n\u00e9cessaires et avons \u00e9galement calcul\u00e9 combien de secouristes civils devraient encore \u00eatre form\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce au soutien de la Fondation Philips, nous avons pu rendre accessibles 44 DAE. La cartographie des emplacements de ces DAE a \u00e9t\u00e9 un travail de pr\u00e9cision. Pour beaucoup, accrocher un DAE au mur est une d\u00e9marche importante. Mais gr\u00e2ce aux nombreuses visites dans les quartiers, \u00e0 la distribution de tracts et \u00e0 la pers\u00e9v\u00e9rance des membres de la Stichting Eindhoven Hartveilig, tous les emplacements ont \u00e9t\u00e9 trouv\u00e9s et il y a maintenant suffisamment de DAE dans la ville.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est important que des DAE soient install\u00e9s partout \u00e0 Eindhoven, mais il est encore plus important que suffisamment de personnes puissent les utiliser. Et c'est pourquoi nous avons organis\u00e9 un \u00e9v\u00e9nement \u00e0 grande \u00e9chelle. Trois coureurs ont port\u00e9 un t-shirt de course sp\u00e9cialement con\u00e7u par Philips pendant le Marathon d'Eindhoven, qui indique la distance jusqu'au DAE le plus proche. Quelle \u00e9nergie de voir autant de personnes se former et quel frisson en entendant les exp\u00e9riences personnelles de tant de personnes. Des histoires remarquables, allant d'histoires tristes sur des proches pour lesquels l'aide est arriv\u00e9e trop tard \u00e0 de belles histoires sur des \u00eatres chers qui sont encore en vie gr\u00e2ce \u00e0 une aide rapide.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je suis tr\u00e8s fier que nous ayons pu atteindre ce jalon ensemble. Gr\u00e2ce aux efforts conjoints de la Philips Foundation, de la Stichting Eindhoven Hartveilig,&nbsp;<strong>Partenaire DEA<\/strong>&nbsp;et gr\u00e2ce \u00e0 de nombreux volontaires, une base solide a \u00e9t\u00e9 pos\u00e9e pour un r\u00e9seau complet dans la ville d'Eindhoven.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Bron :&nbsp;<a href=\"https:\/\/www.linkedin.com\/pulse\/actie-voor-een-hartveilige-stad-eindhoven-geertje-van-keulen\/\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Tijd voor actie! We realiseerden ons dat er nog te veel plekken waren in Eindhoven waar geen binnen 6 minuten hulp mogelijk zou zijn in het geval van een hartstilstand. Vanuit dit pijnlijke inzicht zijn we gestart met het maken van een plan om de stad Eindhoven hartveiliger te maken. Op dat moment is de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"categories":[1],"tags":[],"soort":[3],"class_list":["post-1215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","soort-nieuws"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Samenwerken aan een dekkend AED-netwerk in Eindhoven - AED-Partner<\/title>\n<meta name=\"description\" content=\"Eindhoven Hartveilig, Philips Foundation en AED-Partner werken aan hartveiligheid: met 44 nieuwe AED&#039;s is de basis gelegd voor een dekkend netwerk.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samenwerken aan een dekkend AED-netwerk in Eindhoven - AED-Partner\" \/>\n<meta property=\"og:description\" content=\"Eindhoven Hartveilig, Philips Foundation en AED-Partner werken aan hartveiligheid: met 44 nieuwe AED&#039;s is de basis gelegd voor een dekkend netwerk.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/\" \/>\n<meta property=\"og:site_name\" content=\"AED-Partner\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-31T11:25:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T13:28:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-HartveiligEindhoven.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"818\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#\\\/schema\\\/person\\\/d5aef1c6de94199f91650476e84090fb\"},\"headline\":\"Een hartveilige stad Eindhoven\",\"datePublished\":\"2022-05-31T11:25:27+00:00\",\"dateModified\":\"2026-07-06T13:28:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-HartveiligEindhoven.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/\",\"name\":\"Samenwerken aan een dekkend AED-netwerk in Eindhoven - AED-Partner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-HartveiligEindhoven.png\",\"datePublished\":\"2022-05-31T11:25:27+00:00\",\"dateModified\":\"2026-07-06T13:28:28+00:00\",\"description\":\"Eindhoven Hartveilig, Philips Foundation en AED-Partner werken aan hartveiligheid: met 44 nieuwe AED's is de basis gelegd voor een dekkend netwerk.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-HartveiligEindhoven.png\",\"contentUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-HartveiligEindhoven.png\",\"width\":1340,\"height\":818,\"caption\":\"Vrouw poseert met Philips Heartstart in een woonwijk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/een-hartveilige-stad-eindhoven\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Een hartveilige stad Eindhoven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#website\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/\",\"name\":\"Aedpartner.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#organization\",\"name\":\"AED-Partner\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-Logo-RGB-scaled.png\",\"contentUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-Logo-RGB-scaled.png\",\"width\":2560,\"height\":1372,\"caption\":\"AED-Partner\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#\\\/schema\\\/person\\\/d5aef1c6de94199f91650476e84090fb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/824bd5571911874bcad4dc86bf860ad7eb87cf67e71bef434f6cb133afc270d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/824bd5571911874bcad4dc86bf860ad7eb87cf67e71bef434f6cb133afc270d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/824bd5571911874bcad4dc86bf860ad7eb87cf67e71bef434f6cb133afc270d3?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/serviceshop.a.aedlab.nl\"],\"url\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/be-fr\\\/author\\\/nio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coop\u00e9rer \u00e0 un r\u00e9seau complet de DEE \u00e0 Eindhoven - Partenaire DEE","description":"Eindhoven Hartveilig, Philips Foundation et AED-Partner travaillent \u00e0 la s\u00e9curit\u00e9 cardiaque : avec 44 nouveaux DAE, les bases d'un r\u00e9seau complet sont pos\u00e9es.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Samenwerken aan een dekkend AED-netwerk in Eindhoven - AED-Partner","og_description":"Eindhoven Hartveilig, Philips Foundation en AED-Partner werken aan hartveiligheid: met 44 nieuwe AED's is de basis gelegd voor een dekkend netwerk.","og_url":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/","og_site_name":"AED-Partner","article_published_time":"2022-05-31T11:25:27+00:00","article_modified_time":"2026-07-06T13:28:28+00:00","og_image":[{"width":1340,"height":818,"url":"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-HartveiligEindhoven.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/#article","isPartOf":{"@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/"},"author":{"name":"admin","@id":"https:\/\/serviceshop.aedlab.nl\/#\/schema\/person\/d5aef1c6de94199f91650476e84090fb"},"headline":"Een hartveilige stad Eindhoven","datePublished":"2022-05-31T11:25:27+00:00","dateModified":"2026-07-06T13:28:28+00:00","mainEntityOfPage":{"@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/serviceshop.aedlab.nl\/#organization"},"image":{"@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/#primaryimage"},"thumbnailUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-HartveiligEindhoven.png","articleSection":["Uncategorized"],"inLanguage":"fr-BE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/","url":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/","name":"Coop\u00e9rer \u00e0 un r\u00e9seau complet de DEE \u00e0 Eindhoven - Partenaire DEE","isPartOf":{"@id":"https:\/\/serviceshop.aedlab.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/#primaryimage"},"image":{"@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/#primaryimage"},"thumbnailUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-HartveiligEindhoven.png","datePublished":"2022-05-31T11:25:27+00:00","dateModified":"2026-07-06T13:28:28+00:00","description":"Eindhoven Hartveilig, Philips Foundation et AED-Partner travaillent \u00e0 la s\u00e9curit\u00e9 cardiaque : avec 44 nouveaux DAE, les bases d'un r\u00e9seau complet sont pos\u00e9es.","breadcrumb":{"@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/#primaryimage","url":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-HartveiligEindhoven.png","contentUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-HartveiligEindhoven.png","width":1340,"height":818,"caption":"Vrouw poseert met Philips Heartstart in een woonwijk"},{"@type":"BreadcrumbList","@id":"https:\/\/serviceshop.aedlab.nl\/een-hartveilige-stad-eindhoven\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serviceshop.aedlab.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"Een hartveilige stad Eindhoven"}]},{"@type":"WebSite","@id":"https:\/\/serviceshop.aedlab.nl\/#website","url":"https:\/\/serviceshop.aedlab.nl\/","name":"Aedpartner.com","description":"","publisher":{"@id":"https:\/\/serviceshop.aedlab.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serviceshop.aedlab.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/serviceshop.aedlab.nl\/#organization","name":"Partenaire DEA","url":"https:\/\/serviceshop.aedlab.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/serviceshop.aedlab.nl\/#\/schema\/logo\/image\/","url":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-Logo-RGB-scaled.png","contentUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-Logo-RGB-scaled.png","width":2560,"height":1372,"caption":"AED-Partner"},"image":{"@id":"https:\/\/serviceshop.aedlab.nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/serviceshop.aedlab.nl\/#\/schema\/person\/d5aef1c6de94199f91650476e84090fb","name":"administrateur","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/secure.gravatar.com\/avatar\/824bd5571911874bcad4dc86bf860ad7eb87cf67e71bef434f6cb133afc270d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/824bd5571911874bcad4dc86bf860ad7eb87cf67e71bef434f6cb133afc270d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/824bd5571911874bcad4dc86bf860ad7eb87cf67e71bef434f6cb133afc270d3?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/serviceshop.a.aedlab.nl"],"url":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/author\/nio\/"}]}},"_links":{"self":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/posts\/1215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/comments?post=1215"}],"version-history":[{"count":2,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/posts\/1215\/revisions"}],"predecessor-version":[{"id":1217,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/posts\/1215\/revisions\/1217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/media\/327"}],"wp:attachment":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/media?parent=1215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/categories?post=1215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/tags?post=1215"},{"taxonomy":"soort","embeddable":true,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/soort?post=1215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}