{"id":2560,"date":"2026-02-25T15:28:57","date_gmt":"2026-02-25T15:28:57","guid":{"rendered":"https:\/\/serviceshop.a.aedlab.nl\/?post_type=aed-voor-jouw&#038;p=2560"},"modified":"2026-09-01T15:33:57","modified_gmt":"2026-09-01T13:33:57","slug":"vente-au-detail","status":"publish","type":"aed-voor-jouw","link":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/aed-voor-jouw\/detailhandel\/","title":{"rendered":"Boutique et magasin"},"content":{"rendered":"<section class=\"bde-section-2560-100 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h1 class=\"bde-heading-2560-102 bde-heading\">\nDAE pour le commerce de d\u00e9tail\n<\/h1><\/div>\n<\/section><section class=\"bde-section-2560-103 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-2560-104 bde-columns\"><div class=\"bde-column-2560-105 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-2560-106 bde-image2\" src=\"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel.jpg\" alt=\"Employ\u00e9e de Tuinland pose avec un DAE Mindray L1\" loading=\"lazy\" srcset=\"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel.jpg 1200w, https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel-300x200.jpg 300w, https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel-1024x683.jpg 1024w, https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel-768x512.jpg 768w, https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" data-entrance=\"fade\">\n<\/div><div class=\"bde-column-2560-107 bde-column\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<h2 class=\"bde-heading-2560-108 bde-heading\">\nS\u00e9curit\u00e9 cardiaque dans le supermarch\u00e9, le magasin de bricolage ou le magasin\n<\/h2><div class=\"bde-text-2560-109 bde-text\">\nDans le commerce de d\u00e9tail, vous travaillez avec un grand flux de visiteurs. \u00c0 la caisse, dans une all\u00e9e ou au dernier \u00e9tage : n'importe qui peut faire un arr\u00eat cardiaque n'importe o\u00f9. Avec un DAE, vous pouvez agir imm\u00e9diatement pour sauver des vies dans une telle situation, avant m\u00eame l'arriv\u00e9e des secours professionnels. La s\u00e9curit\u00e9 cardiaque fait ainsi partie int\u00e9grante d'une gestion responsable du magasin.\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-2560-110 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-2560-111 bde-columns\"><div class=\"bde-column-2560-112 bde-column\">\n  \n  \n\t\n\n\n\n<h3 class=\"bde-heading-2560-113 bde-heading\">\nQuel DAE convient \u00e0 un environnement de magasin ?\n<\/h3><div class=\"bde-text-2560-114 bde-text\">\nSur le lieu de vente et dans les entrep\u00f4ts travaillent principalement des collaborateurs sans connaissances m\u00e9dicales. C'est pourquoi la plupart des magasins optent pour un DAE enti\u00e8rement automatique. Ce type de DAE est facile \u00e0 utiliser et vous guide clairement, \u00e9tape par \u00e9tape, tout au long de la r\u00e9animation. Si plusieurs de vos collaborateurs ou visiteurs parlent une autre langue, un DAE multilingue peut faire la diff\u00e9rence en cas d'urgence. Avec notre Assistant de Choix de DAE, d\u00e9couvrez rapidement et gratuitement quel DAE convient \u00e0 votre situation :\n<\/div><div class=\"bde-button-2560-115 bde-button\">\n    \n                        \n                        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"\/be-fr\/aide-au-choix-des-dae\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Aide au Choix DAE (2 min)<\/span>\n\n                            \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-2560-116 bde-column\">\n  \n  \n\t\n\n\n\n<h3 class=\"bde-heading-2560-117 bde-heading\">\nEn bref : DAE pour la vente au d\u00e9tail\n<\/h3><div class=\"bde-icon-list-2560-119 bde-icon-list\">\n<ul>\n  \n              \n    <li>\n              <div class='bde-icon-list__item-wrapper'>\n      \n      <span class='bde-icon-list__icon'>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\"\/><\/svg>\n      <\/span>\n      <span class='bde-icon-list__text' >\n      Les magasins sont des espaces publics \u00e0 forte affluence.\n      <\/span>\n              <\/div>\n      \n    <\/li>\n\n  \n              \n    <li>\n              <div class='bde-icon-list__item-wrapper'>\n      \n      <span class='bde-icon-list__icon'>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\"\/><\/svg>\n      <\/span>\n      <span class='bde-icon-list__text' >\n      Un DAE permet une intervention rapide en cas d'arr\u00eat cardiaque.\n      <\/span>\n              <\/div>\n      \n    <\/li>\n\n  \n              \n    <li>\n              <div class='bde-icon-list__item-wrapper'>\n      \n      <span class='bde-icon-list__icon'>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\"\/><\/svg>\n      <\/span>\n      <span class='bde-icon-list__text' >\n      Convient pour une utilisation par le personnel du magasin.\n      <\/span>\n              <\/div>\n      \n    <\/li>\n\n  \n              \n    <li>\n              <div class='bde-icon-list__item-wrapper'>\n      \n      <span class='bde-icon-list__icon'>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\"\/><\/svg>\n      <\/span>\n      <span class='bde-icon-list__text' >\n      Le positionnement strat\u00e9gique permet d'\u00e9viter les pertes de temps.\n      <\/span>\n              <\/div>\n      \n    <\/li>\n\n  \n              \n    <li>\n              <div class='bde-icon-list__item-wrapper'>\n      \n      <span class='bde-icon-list__icon'>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\"\/><\/svg>\n      <\/span>\n      <span class='bde-icon-list__text' >\n      Entretien n\u00e9cessaire \u00e0 la disponibilit\u00e9 op\u00e9rationnelle.\n      <\/span>\n              <\/div>\n      \n    <\/li>\n\n  <\/ul>\n\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-2560-159 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-2560-160 bde-columns\"><div class=\"bde-column-2560-161 bde-column\">\n  \n  \n\t\n\n\n\n<h3 class=\"bde-heading-2560-162 bde-heading\">\nPourquoi un DAE est-il important dans les magasins ?\n<\/h3><div class=\"bde-text-2560-163 bde-text\">\nLes magasins attirent quotidiennement des publics vari\u00e9s : familles, personnes \u00e2g\u00e9es, clients fid\u00e8les et employ\u00e9s. C'est pr\u00e9cis\u00e9ment dans un environnement avec un tel flux de personnes qu'il existe toujours une possibilit\u00e9 qu'une personne subisse un arr\u00eat cardiaque. Les employ\u00e9s sont souvent les premiers sur les lieux et peuvent agir de mani\u00e8re salvatrice en attendant l'arriv\u00e9e de l'ambulance.<br><br>Un DAE donne des instructions claires et assiste lors de la r\u00e9animation. Il augmente ainsi les chances de survie et offre aux employ\u00e9s un soutien dans une situation stressante. Il contribue \u00e0 un environnement commercial s\u00fbr pour toutes les personnes pr\u00e9sentes dans le b\u00e2timent.<br>\n<\/div>\n<\/div><div class=\"bde-column-2560-164 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-2560-165 bde-image2\" src=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/03\/Wat-zijn-de-symptomen-van-een-hartstilstand.jpg\" alt=\"Deux personnes r\u00e9animent une personne tandis qu&#039;un homme ouvre les \u00e9lectrodes.\" loading=\"lazy\" srcset=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/03\/Wat-zijn-de-symptomen-van-een-hartstilstand.jpg 2084w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/03\/Wat-zijn-de-symptomen-van-een-hartstilstand-300x200.jpg 300w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/03\/Wat-zijn-de-symptomen-van-een-hartstilstand-1024x683.jpg 1024w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/03\/Wat-zijn-de-symptomen-van-een-hartstilstand-768x512.jpg 768w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/03\/Wat-zijn-de-symptomen-van-een-hartstilstand-1536x1024.jpg 1536w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/03\/Wat-zijn-de-symptomen-van-een-hartstilstand-2048x1366.jpg 2048w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/03\/Wat-zijn-de-symptomen-van-een-hartstilstand-18x12.jpg 18w\" sizes=\"(max-width: 2084px) 100vw, 2084px\" data-entrance=\"fade\">\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-2560-120 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-shortcode-2560-172 bde-shortcode\">\n<div class=\"aedshop-product-feed\">\n            <p>Aucun produit trouv\u00e9.<\/p>\n        <div class=\"aedshop-product-feed_items\">\n            <\/div>\n<\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-2560-125 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-2560-126 bde-columns\"><div class=\"bde-column-2560-127 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-2560-157 bde-image2\" src=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel4.jpg\" alt=\"Employ\u00e9 de Mediamarkt court avec un DAE Mindray vers une situation m\u00e9dicale\" loading=\"lazy\" srcset=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel4.jpg 1200w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel4-300x200.jpg 300w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel4-1024x683.jpg 1024w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel4-768x512.jpg 768w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel4-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" data-entrance=\"fade\"><h3 class=\"bde-heading-2560-128 bde-heading\">\nLes d\u00e9taillants sont-ils oblig\u00e9s d'avoir un DAE ?\n<\/h3><div class=\"bde-text-2560-130 bde-text\">\nUn DAE n'est pas une obligation l\u00e9gale pour les magasins ou les supermarch\u00e9s. Cependant, nous avons tous une obligation g\u00e9n\u00e9rale de veiller \u00e0 un environnement s\u00fbr. De plus en plus de d\u00e9taillants int\u00e8grent donc un DAE dans leur politique de s\u00e9curit\u00e9, en particulier pour les grands magasins ou les enseignes multiples.\n<\/div>\n<\/div><div class=\"bde-column-2560-131 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-2560-137 bde-image2\" src=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel5.jpg\" alt=\"Un DEA, sac inclus, est suspendu dans l&#039;entrep\u00f4t d&#039;une quincaillerie.\" loading=\"lazy\" srcset=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel5.jpg 1200w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel5-300x200.jpg 300w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel5-1024x683.jpg 1024w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel5-768x512.jpg 768w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel5-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" data-entrance=\"fade\"><h3 class=\"bde-heading-2560-132 bde-heading\">\nO\u00f9 placez-vous un DAE dans un supermarch\u00e9, un magasin ou une quincaillerie ?\n<\/h3><div class=\"bde-text-2560-134 bde-text\">\nDans le commerce de d\u00e9tail, l'emplacement est synonyme de visibilit\u00e9 et de circulation. Le DAE doit \u00eatre rapidement accessible depuis la surface de vente. Il est important que les employ\u00e9s sachent o\u00f9 se trouve le DAE et qu'il soit facilement accessible. Les emplacements logiques sont pr\u00e8s du comptoir de service ou de l'entr\u00e9e principale, au centre entre plusieurs all\u00e9es ou dans le hall central d'un centre commercial. \n<\/div>\n<\/div><div class=\"bde-column-2560-135 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-2560-156 bde-image2\" src=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel3.jpg\" alt=\"Employ\u00e9 de Mediamarkt pose avec un DAE Mindray dans le magasin\" loading=\"lazy\" srcset=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel3.jpg 1200w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel3-300x200.jpg 300w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel3-1024x683.jpg 1024w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel3-768x512.jpg 768w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-Detailhandel3-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" data-entrance=\"fade\"><h3 class=\"bde-heading-2560-136 bde-heading\">\nCombien co\u00fbte un DAE, maintenance incluse ?\n<\/h3><div class=\"bde-rich-text-2560-173 bde-rich-text breakdance-rich-text-styles\">\n<p>Les co\u00fbts comprennent l'achat, l'installation et la maintenance. L'investissement pr\u00e9cis varie selon le type d'DAE et l'abonnement de service choisi. Si vous avez plusieurs succursales, nous pouvons \u00e9galement organiser la maintenance pour vous de mani\u00e8re centralis\u00e9e. De cette fa\u00e7on, tous les DAE sont contr\u00f4l\u00e9s et g\u00e9r\u00e9s selon le m\u00eame calendrier.<\/p>\n<\/div><div class=\"bde-button-2560-166 bde-button\">\n    \n                                    \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"\/be-fr\/service-a-la-clientele\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Demander un devis<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-2560-139 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h3 class=\"bde-heading-2560-140 bde-heading\">\nQuestions fr\u00e9quemment pos\u00e9es\n<\/h3><div class=\"bde-post-loop-2560-158 bde-post-loop\"><div class=\"bde-loop bde-loop-grid ee-posts ee-posts-grid\">    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-3211-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Qu'est-ce que vous, en tant que client final, remarquez de la MDR ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Achetez-vous ou poss\u00e9dez-vous un DAE pour un usage personnel ? Alors, le MDR ne change rien. Cependant, vous constaterez que certaines marques ou certains mod\u00e8les de DAE ne sont plus en vente. Cela se produit parce que tous les produits ne r\u00e9pondent pas aux nouvelles r\u00e9glementations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00c0 partir du 31 d\u00e9cembre 2027, les DAE ne pourront plus \u00eatre vendus sans certificat MDR. Si vous, en tant que client final, poss\u00e9dez un DAE avec un certificat MDD, vous pourrez continuer \u00e0 l'utiliser apr\u00e8s le 31 d\u00e9cembre 2027.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Achetez-vous un DAE et le revendez-vous \u00e0 quelqu'un d'autre ? Alors vous vendez un dispositif m\u00e9dical. Toutes les obligations du MDR qui s'appliquent \u00e0 AED-Partner en tant que vendeur s'appliquent \u00e9galement \u00e0 vous en tant que revendeur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avez-vous une question concernant votre DAE et le MDR ? Nos \u00e9quipes du <a href=\"\/be-fr\/contact\/\" type=\"link\" id=\"\/contact\">Customer Service<\/a> connaissent parfaitement les appareils et vous offrent des conseils gratuits.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-3221-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Comment puis-je retournerner un produit ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Vous avez achet\u00e9 un DAE ou un autre produit chez AED-Partner et vous n'\u00eates pas satisfait ? En tant que consommateur, vous disposez du droit l\u00e9gal de r\u00e9tractation pour retourner votre achat dans les 14 jours suivant sa r\u00e9ception. Pour ce faire, vous pouvez remplir notre <a href=\"\/be-fr\/retourneren\/\" data-type=\"link\" data-id=\"\/nl\/retourneren\/\">formulaire de retour<\/a> .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-4746-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Un DAE d'entra\u00eenement peut-il donner un vrai choc ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Un DAE d'entra\u00eenement est destin\u00e9 \u00e0 la formation et ne peut jamais d\u00e9livrer de choc \u00e9lectrique r\u00e9el. Cela permet aux participants de s'entra\u00eener \u00e0 la r\u00e9animation et \u00e0 l'utilisation d'un DAE de mani\u00e8re r\u00e9aliste et s\u00fbre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-4888-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Comment conserver au mieux un mannequin de r\u00e9animation ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Pour une utilisation durable d'un mannequin de r\u00e9animation ou d'\u00e9touffement, il est important de toujours le ranger en toute s\u00e9curit\u00e9 et de le transporter \u00e0 l'abri. Assurez-vous que le mannequin est conserv\u00e9 au sec, \u00e0 l'abri de la poussi\u00e8re et \u00e0 temp\u00e9rature ambiante, par exemple en le rangeant dans un sac ou une mallette sp\u00e9ciale. Il est \u00e9galement important de ne pas placer d'objets lourds sur le mannequin. Vous \u00e9viterez ainsi que le mannequin ne soit endommag\u00e9.<\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-4984-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Quels accessoires avez-vous besoin pour une formation de r\u00e9animation ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">En plus d'un mannequin de r\u00e9animation, des sacs pulmonaires (jetables) suppl\u00e9mentaires, des peaux de visage, des lingettes d\u00e9sinfectantes, un sac de transport et un DAE d'entra\u00eenement sont \u00e9galement utiles. Utilisez-vous un mannequin de r\u00e9animation avanc\u00e9 ? Vous pouvez alors \u00e9galement t\u00e9l\u00e9charger et utiliser l'application correspondante.<\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-3008-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Peut-on utiliser un DAE avec des gants de travail ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Non. La plupart des DEA sont dot\u00e9s de gros boutons ou d'un \u00e9cran tactile que vous pouvez utiliser avec des gants, tels que des gants chauds (d'hiver) ou des gants de travail. Il est toutefois pr\u00e9f\u00e9rable d'enlever ses gants (de travail). Il est ainsi plus facile de d\u00e9boutonner une chemise ou un soutien-gorge avec les ciseaux du kit de sauvetage. Les gants de travail emp\u00eachent \u00e9galement de coller correctement les \u00e9lectrodes sur la poitrine de la victime. Enlevez toujours vos gants d\u00e8s que vous commencez la RCP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez bien s\u00fbr utiliser un DAE avec les gants jetables en nitrile (hygi\u00e9niques) de la trousse de secours.<\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-3021-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Quels sont les \u00e9lectrodes p\u00e9diatriques et quand les utilise-t-on ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Les \u00e9lectrodes p\u00e9diatriques sont des autocollants sp\u00e9ciaux qui r\u00e9duisent le niveau de courant du choc. Vous les utilisez pour les enfants jusqu'\u00e0 environ 8 ans ou jusqu'\u00e0 un poids de 25 kilos. En raison de la plus petite taille des \u00e9lectrodes et du niveau d'\u00e9nergie plus bas, le choc \u00e9lectrique d\u00e9livr\u00e9 par le DAE est mieux adapt\u00e9 au corps plus petit d'un enfant.<\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-3025-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Comment prot\u00e9ger un DAE contre le vandalisme ou le vol ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Vous prot\u00e9gez un DAE en le pla\u00e7ant dans un bo\u00eetier ext\u00e9rieur robuste. Ces bo\u00eetiers sont souvent fabriqu\u00e9s dans des mat\u00e9riaux r\u00e9sistants aux chocs et sont \u00e9galement disponibles avec des options de s\u00e9curit\u00e9 suppl\u00e9mentaires telles qu'une serrure \u00e0 code PIN ou une alarme qui se d\u00e9clenche d\u00e8s que le bo\u00eetier est ouvert.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez \u00e9galement pr\u00e9venir le vandalisme et le vol en pla\u00e7ant le placard dans un endroit bien en vue (fr\u00e9quent\u00e9), \u00e0 la vue des cam\u00e9ras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chez AED-Partner, vous pouvez aussi un <a href=\"https:\/\/serviceshop.a.aedlab.nl\/shop\/aed-partner-diefstal-verzekering\">assurance vol<\/a> cl\u00f4ture. Votre DAE est-il vol\u00e9 ? Nous nous assurons que vous recevez rapidement un DAE de remplacement.<\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-3026-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Quel DAE convient \u00e0 l'aviation ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Les DAE pour l'aviation doivent \u00eatre conformes \u00e0 des certifications sp\u00e9cifiques (marquage TSO). Ces appareils sont test\u00e9s sur des facteurs tels que les diff\u00e9rences de pression atmosph\u00e9rique et les rayonnements \u00e9lectromagn\u00e9tiques, afin de ne pas perturber les syst\u00e8mes de bord d'un avion. Tous les mod\u00e8les standards ne peuvent pas \u00eatre emport\u00e9s \u00e0 bord d'un avion commercial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour des questions plus sp\u00e9cifiques \u00e0 ce sujet, veuillez contacter notre <a href=\"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/service-a-la-clientele\/\">Customer Service<\/a>.<\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n    <article class=\"bde-loop-item ee-post\">\n        <div class=\"bde-frequently-asked-questions-2803-101-3144-2803-1 bde-frequently-asked-questions bde-frequently-asked-questions-2803-101\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-101-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-101-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Faut-il brancher un DAE sur une prise de courant ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 363.3c6.2 6.2 16.4 6.2 22.6 0l160-160c6.2-6.2 6.2-16.4 0-22.6s-16.4-6.2-22.6 0L192 329.4 43.3 180.7c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6l160 160z\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><!--! Font Awesome Pro 7.0.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2025 Fonticons, Inc. --><path fill=\"currentColor\" d=\"M180.7 148.7c6.2-6.2 16.4-6.2 22.6 0l160 160c6.2 6.2 6.2 16.4 0 22.6s-16.4 6.2-22.6 0L192 182.6 43.3 331.3c-6.2 6.2-16.4 6.2-22.6 0s-6.2-16.4 0-22.6l160-160z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-101-button-1\" id=\"bde-faq-101-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\">\n<p class=\"wp-block-paragraph\">Un DAE fonctionne avec une batterie sp\u00e9ciale pour DAE. Il n'est donc pas n\u00e9cessaire de connecter le DAE au r\u00e9seau \u00e9lectrique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous placez le DAE dans un casier pour DAE avec un code PIN, une ventilation, un refroidissement, un chauffage et\/ou une connexion Wi-Fi, le casier pour DAE a besoin d'\u00e9lectricit\u00e9 et vous devez connecter le casier \u00e0 une prise de courant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes sp\u00e9cialis\u00e9s dans <a href=\"https:\/\/serviceshop.a.aedlab.nl\/shop\/groep\/kasten\">Armoires pour DAE<\/a> et peuvent \u00e9galement vous aider \u00e0 installer l'armoire DAE appropri\u00e9e au bon endroit. Souhaitez-vous en savoir plus ? Notre <a href=\"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/service-a-la-clientele\/\">Customer Service<\/a> est heureux de vous aider.<\/p>\n<\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>    <\/article>\n<\/div>\r\n<\/div><\/div>\n<\/section><section class=\"bde-section-2560-146 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-2560-147 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-columns-2560-148 bde-columns\"><div class=\"bde-column-2560-149 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-dual-heading-2560-150 bde-dual-heading\">\n\n\n            <span data-style=\"primary\" class=\"dual-heading--primary\">Obtenir<\/span>\n\n            <span data-style=\"secondary\" class=\"dual-heading--secondary\">sans obligation<\/span>\n\n            <span data-style=\"primary\" class=\"dual-heading--primary\"> une consultation personnelle + une offre<\/span>\n\n\n\n<\/h2><div class=\"bde-rich-text-2560-151 bde-rich-text breakdance-rich-text-styles\">\n<p>Pour une assistance rapide, veuillez nous contacter par t\u00e9l\u00e9phone au <a href=\"tel:+3211420345\">+31 (0)499 49 00 16<\/a>. Ou laissez vos coordonn\u00e9es via le formulaire. Notre personnel est \u00e0 votre disposition les jours ouvrables entre 8h30 et 18h00.<\/p>\n<\/div><div class=\"bde-globalblock-2560-174 bde-globalblock\"><\/div>\n<\/div><div class=\"bde-column-2560-153 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-2560-154 bde-image2\" src=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-AED-offerte8.png\" alt=\"Un homme et une femme posent avec un Powerheart G5 et un Zoll AED+\" loading=\"lazy\" srcset=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-AED-offerte8.png 1200w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-AED-offerte8-290x300.png 290w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-AED-offerte8-989x1024.png 989w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-AED-offerte8-768x795.png 768w, https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-AED-offerte8-12x12.png 12w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-2560-155 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><\/div>\n<\/section>","protected":false},"featured_media":2561,"template":"","meta":{"_acf_changed":true,"_breakdance_hide_in_design_set":false,"_breakdance_tags":""},"class_list":["post-2560","aed-voor-jouw","type-aed-voor-jouw","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AED kopen als winkel? Kosten, tips &amp; advies - AED-Partner<\/title>\n<meta name=\"description\" content=\"Zoek je een AED voor jouw winkel of supermarkt? Lees alles over de kosten, slimme plaatsing en gebruik onze gratis AED Keuzehulp voor productadvies.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AED kopen als winkel? Kosten, tips &amp; advies - AED-Partner\" \/>\n<meta property=\"og:description\" content=\"Zoek je een AED voor jouw winkel of supermarkt? Lees alles over de kosten, slimme plaatsing en gebruik onze gratis AED Keuzehulp voor productadvies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/\" \/>\n<meta property=\"og:site_name\" content=\"AED-Partner\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T13:33:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/aed-voor-jouw\\\/detailhandel\\\/\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/aed-voor-jouw\\\/detailhandel\\\/\",\"name\":\"AED kopen als winkel? Kosten, tips & advies - AED-Partner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/aed-voor-jouw\\\/detailhandel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/aed-voor-jouw\\\/detailhandel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/AED-Partner-detailhandel.jpg\",\"datePublished\":\"2026-02-25T15:28:57+00:00\",\"dateModified\":\"2026-09-01T13:33:57+00:00\",\"description\":\"Zoek je een AED voor jouw winkel of supermarkt? Lees alles over de kosten, slimme plaatsing en gebruik onze gratis AED Keuzehulp voor productadvies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/aed-voor-jouw\\\/detailhandel\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/aed-voor-jouw\\\/detailhandel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/aed-voor-jouw\\\/detailhandel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/AED-Partner-detailhandel.jpg\",\"contentUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/AED-Partner-detailhandel.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Medewerkster van de Tuinland poseert met een Mindray L1 AED\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/aed-voor-jouw\\\/detailhandel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detailhandel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#website\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/\",\"name\":\"Aedpartner.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#organization\",\"name\":\"AED-Partner\",\"url\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-Logo-RGB-scaled.png\",\"contentUrl\":\"https:\\\/\\\/serviceshop.a.aedlab.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AED-Partner-Logo-RGB-scaled.png\",\"width\":2560,\"height\":1372,\"caption\":\"AED-Partner\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceshop.aedlab.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acheter un DAE en tant que magasin ? Co\u00fbts, conseils et avis - AED-Partner","description":"Vous cherchez un DAE pour votre magasin ou votre supermarch\u00e9 ? Lisez tout sur les co\u00fbts, le placement intelligent et utilisez notre aide au choix DAE gratuite pour des conseils sur les produits.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"AED kopen als winkel? Kosten, tips & advies - AED-Partner","og_description":"Zoek je een AED voor jouw winkel of supermarkt? Lees alles over de kosten, slimme plaatsing en gebruik onze gratis AED Keuzehulp voor productadvies.","og_url":"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/","og_site_name":"AED-Partner","article_modified_time":"2026-09-01T13:33:57+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/serviceshop.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/","url":"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/","name":"Acheter un DAE en tant que magasin ? Co\u00fbts, conseils et avis - AED-Partner","isPartOf":{"@id":"https:\/\/serviceshop.aedlab.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/#primaryimage"},"image":{"@id":"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/#primaryimage"},"thumbnailUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel.jpg","datePublished":"2026-02-25T15:28:57+00:00","dateModified":"2026-09-01T13:33:57+00:00","description":"Vous cherchez un DAE pour votre magasin ou votre supermarch\u00e9 ? Lisez tout sur les co\u00fbts, le placement intelligent et utilisez notre aide au choix DAE gratuite pour des conseils sur les produits.","breadcrumb":{"@id":"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/#primaryimage","url":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel.jpg","contentUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2026\/02\/AED-Partner-detailhandel.jpg","width":1200,"height":800,"caption":"Medewerkster van de Tuinland poseert met een Mindray L1 AED"},{"@type":"BreadcrumbList","@id":"https:\/\/serviceshop.aedlab.nl\/nl\/aed-voor-jouw\/detailhandel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serviceshop.aedlab.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"Detailhandel"}]},{"@type":"WebSite","@id":"https:\/\/serviceshop.aedlab.nl\/#website","url":"https:\/\/serviceshop.aedlab.nl\/","name":"Aedpartner.com","description":"","publisher":{"@id":"https:\/\/serviceshop.aedlab.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serviceshop.aedlab.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/serviceshop.aedlab.nl\/#organization","name":"Partenaire DEA","url":"https:\/\/serviceshop.aedlab.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/serviceshop.aedlab.nl\/#\/schema\/logo\/image\/","url":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-Logo-RGB-scaled.png","contentUrl":"https:\/\/serviceshop.a.aedlab.nl\/wp-content\/uploads\/2025\/10\/AED-Partner-Logo-RGB-scaled.png","width":2560,"height":1372,"caption":"AED-Partner"},"image":{"@id":"https:\/\/serviceshop.aedlab.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/aed-voor-jouw\/2560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/aed-voor-jouw"}],"about":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/types\/aed-voor-jouw"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/media\/2561"}],"wp:attachment":[{"href":"https:\/\/serviceshop.a.aedlab.nl\/be-fr\/wp-json\/wp\/v2\/media?parent=2560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}